{"id":129571,"date":"2025-02-12T18:06:30","date_gmt":"2025-02-12T18:06:30","guid":{"rendered":"https:\/\/qrealo.cl\/vermontmedellin\/index.php\/2025\/02\/12\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/"},"modified":"2025-02-12T18:06:30","modified_gmt":"2025-02-12T18:06:30","slug":"pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que","status":"publish","type":"blog","link":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/","title":{"rendered":"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9?"},"content":{"rendered":"<p><span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\"><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">El ejercicio docente diariamente nos presenta desaf\u00edos y avatares que nos limitan en cierta medida nuestros espacios para reflexionar y considerar la esencia y el porqu\u00e9 de nuestras pr\u00e1cticas. Con frecuencia nos encontramos llevando a cabo acciones que por alg\u00fan motivo se vieron enmarcados en las pautas y estatutos que gu\u00edan nuestro quehacer docente y en virtud de esto las realizamos sin preguntar m\u00e1s. Hoy, sin embargo quisiera tomarme algunos minutos para reflexionar sobre una de ellas, las pruebas estandarizadas SABER, antes conocidas como Icfes.<\/span><\/p>\n<p> <!--more--> <\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\"><strong>En nuestro equipo de trabajo las preguntas que m\u00e1s frecuentemente surgen respecto a estas se refieren al c\u00f3mo.<\/strong> Invertimos gran cantidad de tiempo planeando su preparaci\u00f3n, generando material did\u00e1ctico para apoyar dicha preparaci\u00f3n, estableciendo incentivos para los estudiantes y espacios de toda \u00edndole e incluso en numerosas ocasiones sacrificando otros espacios formativos de gran importancia para favorecer la obtenci\u00f3n de unos resultados que puedan, entre comillas, reflejar la calidad del proceso educativo.<\/span><\/p>\n<p><span style=\"color: #000000\"><img decoding=\"async\" src=\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/books-3071110_640-Feb-28-2024-10-33-57-2513-PM.jpg\" alt=\"books-3071110_640\" width=\"1000\" style=\"width: 1000px;margin: 0px auto\"><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">Sin embargo, este af\u00e1n, a veces desmedido de mostrar resultados en estas pruebas tiene un precio. <strong>El impacto que se genera a partir de estas pr\u00e1cticas se puede evidenciar en varios frentes, comenzando por la capacidad de abordar con suficiencia los contenidos y competencias planteados para cada uno de estos \u00faltimos a\u00f1os escolares<\/strong>, adem\u00e1s de una apropiada preparaci\u00f3n para la inserci\u00f3n en el mundo de la educaci\u00f3n superior, pasando por amplias inversiones monetarias que realizan tanto las instituciones como las familias; pero lo m\u00e1s importante y tal vez devastador, el efecto que este proceso tiene en la motivaci\u00f3n de nuestros estudiantes, quienes con frecuencia manifiestan no entender completamente cual es el incentivo real de su sacrificio y dedicaci\u00f3n durante este proceso.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">Como educadores es tambi\u00e9n nuestro deber inquietarnos sobre esta cuesti\u00f3n. Es por esto que quisiera dedicar algunas l\u00edneas para considerar algunas situaciones relacionadas con el tema y analizar la influencia que tienen en dichas pr\u00e1cticas. Para lo anterior, y como en cualquier otra situaci\u00f3n, creo que es pertinente empezar por el por qu\u00e9.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">En la p\u00e1gina web del Ministerio de Educaci\u00f3n nacional se lee la siguiente cita por parte del entonces director del ICFES, Daniel Bogoya: <em>&#8220;Queremos apreciar c\u00f3mo entienden los estudiantes cada uno de los dominios conceptuales y c\u00f3mo resuelven problemas. Los resultados de estas pruebas est\u00e1n a disposici\u00f3n de las entidades territoriales, y las instituciones deben iniciar su estudio y an\u00e1lisis con el fin de dise\u00f1ar su propio Plan de Mejoramiento&#8221;. <\/em>A partir de esto se entiende que el objetivo de las pruebas es dar elementos a las instituciones educativas y entidades territoriales para plantear procesos que propendan por el mejoramiento de la calidad educativa.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">Esto levanta un nuevo interrogante y es: \u00bfen qu\u00e9 momento las pruebas SABER abandonaron este objetivo tan noble y se convirtieron en un par\u00e1metro para clasificar y posicionar instituciones educativas en relaci\u00f3n a la calidad de sus procesos educativos? Y es que es necesario hacerse esta pregunta porque de este car\u00e1cter ordinal, y no de la intenci\u00f3n original, es de donde se desprenden la mayor\u00eda de los efectos no deseados de las pruebas SABER en las diferentes instancias de nuestras instituciones.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">Lo anterior nos invita a realizar una nueva indagaci\u00f3n: \u00bfqu\u00e9 o qui\u00e9n se beneficia de la existencia de las pruebas? Idealmente nos ver\u00edamos tentados a responder que los principales beneficiarios de este sistema son los estudiantes, quienes a trav\u00e9s de ellas pueden acceder a un minucioso diagn\u00f3stico del alcance de los objetivos al culminar su escolaridad a partir del cual se puedan emprender acciones remediales para realizar ajustes frente a su vida universitaria y profesional, pero este no es el caso. Podr\u00eda tambi\u00e9n argumentarse que aquellos estudiantes con desempe\u00f1os sobresalientes pueden acceder a mejores universidades e incluso a becas, pero personalmente creo que esto ser\u00eda mejor determinado a partir de la historia acad\u00e9mica y comportamental del estudiante durante su escolaridad en lugar de una sola prueba.<\/span><\/p>\n<p><span style=\"color: #000000\"><img decoding=\"async\" src=\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/school-1782427_640.jpg\" alt=\"school-1782427_640\" width=\"1000\" style=\"width: 1000px;margin: 0px auto\"><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">Dicho esto, es menester mirar de nuevo la situaci\u00f3n y determinar en realidad quienes son los beneficiados de este sistema. <strong>\u00bfSeremos nosotros como docentes que logramos cada a\u00f1o reafirmarnos en nuestras plazas a partir de unos resultados positivos en nuestras asignaturas?<\/strong> \u00bfSer\u00e1n los colegios, que pueden acceder a un mejor posicionamiento en el mercado a partir de sus resultados y as\u00ed obtener r\u00e9ditos econ\u00f3micos? \u00bfSer\u00e1n las personalidades pol\u00edticas que sin pudor promulgan el mejoramiento de la educaci\u00f3n como consignas de sus campa\u00f1as? \u00bfSer\u00e1n empresas como Elmer Pardo, Milton Ochoa, Instruimos, Formarte y muchas otras que proliferan en nuestro pa\u00eds como producto del af\u00e1n desmedido de las instituciones por mejorar sus resultados?<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #666666\">El prop\u00f3sito de este art\u00edculo no es en ning\u00fan momento descalificar la naturaleza misma de las pruebas como elemento diagn\u00f3stico e insumo para el mejoramiento de los procesos educativos, faceta en la cual se observa con claridad durante las jornadas \u201cD\u00eda E\u201d. <strong>Mi objetivo es llamar la atenci\u00f3n frente a un efecto colateral que se desprende de estas en el cual se promueve una competencia malsana que poco atiende al bienestar de nuestros estudiantes.<\/strong> Una competencia que sirve a su vez como caldo de cultivo para situaciones tales como el fraude masivo y sistem\u00e1tico que se ha presentado en algunas regiones de nuestro pa\u00eds en donde las instituciones de educaci\u00f3n superior entienden dichos resultados como criterio fundamental de admisi\u00f3n a sus programas. Una competencia en la que al parecer los mayores perdedores son los estudiantes mismos.<\/span><\/p>\n<p style=\"text-align: center\"><span style=\"color: #666666\"><span style=\"color: #000000\"><strong>Por: <\/strong>Hern\u00e1n David Gonz\u00e1lez &#8211; Docente<\/span><\/span><\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pruebas estandarizadas: consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9?<\/p>\n","protected":false},"featured_media":20,"template":"","class_list":["post-129571","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9? - Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9? - Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin\" \/>\n<meta property=\"og:description\" content=\"Pruebas estandarizadas: consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/\" \/>\n<meta property=\"og:site_name\" content=\"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vermontschooloficial\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/books-3071110_640-Feb-28-2024-10-33-57-2513-PM.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@vermontschoolm\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/\",\"url\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/\",\"name\":\"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9? - Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin\",\"isPartOf\":{\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/2259-scaled-1.jpg\",\"datePublished\":\"2025-02-12T18:06:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#primaryimage\",\"url\":\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/2259-scaled-1.jpg\",\"contentUrl\":\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/2259-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/vermontmedellin.edu.co\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#website\",\"url\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/\",\"name\":\"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin\",\"description\":\"Blog VermontSchool\",\"publisher\":{\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#organization\",\"name\":\"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin\",\"url\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2024\/04\/vermont-logo-cropped.png\",\"contentUrl\":\"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2024\/04\/vermont-logo-cropped.png\",\"width\":609,\"height\":328,\"caption\":\"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin\"},\"image\":{\"@id\":\"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vermontschooloficial\",\"https:\/\/x.com\/vermontschoolm\",\"https:\/\/www.instagram.com\/vermontschooloficial\/\",\"https:\/\/www.youtube.com\/@VermontSchoolOficial\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9? - Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/","og_locale":"es_ES","og_type":"article","og_title":"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9? - Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin","og_description":"Pruebas estandarizadas: consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9?","og_url":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/","og_site_name":"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin","article_publisher":"https:\/\/www.facebook.com\/vermontschooloficial","og_image":[{"url":"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/books-3071110_640-Feb-28-2024-10-33-57-2513-PM.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@vermontschoolm","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/","url":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/","name":"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9? - Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin","isPartOf":{"@id":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#primaryimage"},"image":{"@id":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#primaryimage"},"thumbnailUrl":"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/2259-scaled-1.jpg","datePublished":"2025-02-12T18:06:30+00:00","breadcrumb":{"@id":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#primaryimage","url":"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/2259-scaled-1.jpg","contentUrl":"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2025\/02\/2259-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/vermontmedellin.edu.co\/es\/blog\/pruebas-estandarizadas-consideraciones-de-un-docente-sobre-el-por-que-y-para-que\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vermontmedellin.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"Pruebas estandarizadas: Consideraciones de un docente sobre el \u00bfpor qu\u00e9 y para qu\u00e9?"}]},{"@type":"WebSite","@id":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#website","url":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/","name":"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin","description":"Blog VermontSchool","publisher":{"@id":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#organization","name":"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin","url":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2024\/04\/vermont-logo-cropped.png","contentUrl":"https:\/\/vermontmedellin.edu.co\/wp-content\/uploads\/sites\/35\/2024\/04\/vermont-logo-cropped.png","width":609,"height":328,"caption":"Vermont School Medell\u00edn, un colegio Cognita Redcol - Colegio Vermont School Medellin"},"image":{"@id":"https:\/\/vermontmedellin.edu.co\/es\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vermontschooloficial","https:\/\/x.com\/vermontschoolm","https:\/\/www.instagram.com\/vermontschooloficial\/","https:\/\/www.youtube.com\/@VermontSchoolOficial"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/vermontmedellin.edu.co\/es\/wp-json\/wp\/v2\/blog\/129571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vermontmedellin.edu.co\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/vermontmedellin.edu.co\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/vermontmedellin.edu.co\/es\/wp-json\/wp\/v2\/blog\/129571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vermontmedellin.edu.co\/es\/wp-json\/wp\/v2\/media\/20"}],"wp:attachment":[{"href":"https:\/\/vermontmedellin.edu.co\/es\/wp-json\/wp\/v2\/media?parent=129571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}